{"id":167,"count":1,"description":"","link":"https:\/\/rideon.es\/en\/category\/lugar-interes\/","name":"Lugares de inter\u00e9s","slug":"lugar-interes","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lugares de inter\u00e9s archivos - Rent a Scooter in Barcelona, Menorca, Mallorca - Ride On Scooter Rental<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lugares de inter\u00e9s Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rideon.es\/en\/category\/lugar-interes\/\" \/>\n<meta property=\"og:site_name\" content=\"Rent a Scooter in Barcelona, Menorca, Mallorca - Ride On Scooter Rental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/rideon.es\\\/en\\\/category\\\/lugar-interes\\\/\",\"url\":\"https:\\\/\\\/rideon.es\\\/en\\\/category\\\/lugar-interes\\\/\",\"name\":\"Lugares de inter\u00e9s archivos - Rent a Scooter in Barcelona, Menorca, Mallorca - Ride On Scooter Rental\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rideon.es\\\/en\\\/#website\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rideon.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/rideon.es\\\/en\\\/\",\"name\":\"Rent a Scooter in Barcelona, Menorca, Mallorca - Ride On Scooter Rental\",\"description\":\"Alquiler de scooters en Barcelona, Menorca, Mallorca y Madrid\",\"publisher\":{\"@id\":\"https:\\\/\\\/rideon.es\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rideon.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rideon.es\\\/en\\\/#organization\",\"name\":\"Rent a Scooter in Barcelona, Menorca, Mallorca - Ride On Scooter Rental\",\"url\":\"https:\\\/\\\/rideon.es\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/rideon.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rideon.es\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2020\\\/02\\\/rideon_logo-200x78-1.png\",\"contentUrl\":\"https:\\\/\\\/rideon.es\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2020\\\/02\\\/rideon_logo-200x78-1.png\",\"width\":200,\"height\":78,\"caption\":\"Rent a Scooter in Barcelona, Menorca, Mallorca - Ride On Scooter Rental\"},\"image\":{\"@id\":\"https:\\\/\\\/rideon.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lugares de inter\u00e9s archivos - Rent a Scooter in Barcelona, Menorca, Mallorca - Ride On Scooter Rental","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"Lugares de inter\u00e9s Archives","og_url":"https:\/\/rideon.es\/en\/category\/lugar-interes\/","og_site_name":"Rent a Scooter in Barcelona, Menorca, Mallorca - Ride On Scooter Rental","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/rideon.es\/en\/category\/lugar-interes\/","url":"https:\/\/rideon.es\/en\/category\/lugar-interes\/","name":"Lugares de inter\u00e9s archivos - Rent a Scooter in Barcelona, Menorca, Mallorca - Ride On Scooter Rental","isPartOf":{"@id":"https:\/\/rideon.es\/en\/#website"},"inLanguage":"en-GB"},{"@type":"WebSite","@id":"https:\/\/rideon.es\/en\/#website","url":"https:\/\/rideon.es\/en\/","name":"Rent a Scooter in Barcelona, Menorca, Mallorca - Ride On Scooter Rental","description":"Alquiler de scooters en Barcelona, Menorca, Mallorca y Madrid","publisher":{"@id":"https:\/\/rideon.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rideon.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/rideon.es\/en\/#organization","name":"Rent a Scooter in Barcelona, Menorca, Mallorca - Ride On Scooter Rental","url":"https:\/\/rideon.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/rideon.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/rideon.es\/en\/wp-content\/uploads\/sites\/14\/2020\/02\/rideon_logo-200x78-1.png","contentUrl":"https:\/\/rideon.es\/en\/wp-content\/uploads\/sites\/14\/2020\/02\/rideon_logo-200x78-1.png","width":200,"height":78,"caption":"Rent a Scooter in Barcelona, Menorca, Mallorca - Ride On Scooter Rental"},"image":{"@id":"https:\/\/rideon.es\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/rideon.es\/en\/wp-json\/wp\/v2\/categories\/167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rideon.es\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/rideon.es\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/rideon.es\/en\/wp-json\/wp\/v2\/posts?categories=167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}